{"id":514,"date":"2019-01-18T00:00:00","date_gmt":"2019-01-17T23:00:00","guid":{"rendered":"https:\/\/seasolar.ch\/offerta-impianto-fotovoltaico-con-accumulo-chiavi-in-mano-4-5kw-smart-poly-ess-9-6\/"},"modified":"2019-01-18T00:00:00","modified_gmt":"2019-01-17T23:00:00","slug":"offerta-impianto-fotovoltaico-con-accumulo-chiavi-in-mano-4-5kw-smart-poly-ess-9-6","status":"publish","type":"post","link":"https:\/\/seasolar.ch\/de\/offerta-impianto-fotovoltaico-con-accumulo-chiavi-in-mano-4-5kw-smart-poly-ess-9-6\/","title":{"rendered":"Offerta Impianto fotovoltaico con accumulo chiavi in mano 4.5kW SMART POLY ESS 9.6"},"content":{"rendered":"<h2>Offerta Impianto fotovoltaico con accumulo &#8222;chiavi in mano&#8220; 4.5kW SMART POLY ESS 9.6<br \/>\nPrezzo su richiesta<\/h2>\n<p>Seasolar offre la possibilit\u00e0 di scegliere quattro linee di offerta chiavi in mano (BASIC, SMART, PREMIUM, ULTRA) con la garanzia del miglior servizio di installazione eseguito da tecnici specializzati per il massimo dell\u2019efficienza e della sicurezza: tutti gli impianti sono garantiti per 24 mesi.<\/p>\n<p>Seasolar propone un impianto fotovoltaico con il sistema di accumulo dell&#8217;energia (Energy Storage System-ESS): il sistema di accumulo \u00e8 del tipo &#8222;bidirezionale lato-produzione&#8220; con accoppiamento in corrente continua (DC-Coupling) direttamente all&#8217;inverter per massimizzare i benefici del tuo impianto fotovoltaico.<\/p>\n<p>L\u2019impianto fotovoltaico con accumulo SMART ha una potenza nominale uguale o superiore a 4,48 KWp e comprende:<\/p>\n<ul>\n<li>16 Moduli fotovoltaici in silicio policristallino a 60 celle (dim. 1650x1000x35mm.) di potenza minima 280 Wp di marca a scelta tra Canadian Solar, Hanwha Q-Cells, JA Solar, Jinko Solar, Trina Solar, garanzia 10 anni<\/li>\n<li>Inverter ibrido monofase di marca GOODWE potenza 3680 W con sistema di monitoraggio e WI-FI integrati, uscita back-up, funzione UPS-Uninterrupted Power Supply (AST-Automatic Switch Time=10ms), battery charger 2500W, garanzia 10 anni estendibile a 20<\/li>\n<li>Batteria agli ioni di litio di marca PYLON capacit\u00e0 9,6 kWh, garanzia 10 anni<\/li>\n<li>Strutture di sostegno in alluminio, garanzia 10 anni.<\/li>\n<\/ul>\n<p>L\u2019installazione inclusa nel prezzo prevede:<\/p>\n<ul>\n<li>montaggio delle strutture di supporto su copertura a falda inclinata;<\/li>\n<li>predisposizione del cablaggio (vie cavo: forometrie, tubazioni, canalizzazioni);<\/li>\n<li>posa dei moduli fotovoltaici su struttura di sostegno;<\/li>\n<li>cablaggio e collegamento;<\/li>\n<li>installazione inverter;<\/li>\n<li>connessione alla rete (compresi contatti e sopralluoghi con distributore locale);<\/li>\n<li>installazione e configurazione del sistema di accumulo, dei moduli batteria aggiuntivi ove acquistati, nonch\u00e9 la predisposizione dell\u2019 impianto elettrico per la funzione di back-up;<\/li>\n<li>installazione e la configurazione del sistema di monitoraggio ove acquistato;<\/li>\n<li>verifiche e collaudo;<\/li>\n<li>pulizia aree di lavoro;<\/li>\n<li>smaltimento imballaggi e rifiuti prodotti con l\u2019attivit\u00e0;<\/li>\n<li>dichiarazione di conformit\u00e0;<\/li>\n<li>oneri sicurezza.<\/li>\n<\/ul>\n<p>Per le attivit\u00e0 di gestione e smaltimento dell\u2019impianto eventualmente sostituito (RAEE), Seasolar si avvale di soggetti terzi che possiedono le caratteristiche e i requisiti obbligatori per legge per svolgere tali attivit\u00e0.<\/p>\n<p>L\u2019offerta &#8222;chiavi in mano&#8220; prevede lo sviluppo progettuale dell\u2019impianto, compresa la predisposizione degli elaborati tecnici richiesti dalle autorit\u00e0 competenti per l\u2019ottenimento delle autorizzazioni necessarie alla realizzazione e all&#8217;entrata in esercizio degli impianti (ad esclusione della relazione tecnica di cui all&#8217;art. 28 L. 10\/91 s.m.i. ove richiesta).<\/p>\n<p>L\u2019offerta &#8222;chiavi in mano&#8220; prevede il supporto del Distributore di rete locale per la Richiesta di Connessione dell\u2019impianto alla rete elettrica, nonch\u00e9 per l\u2019intero iter di connessione comprensivo dello scambio dei relativi documenti, inclusa la compilazione della modulistica, la predisposizione della documentazione,\u00a0nonch\u00e9 la gestione dell\u2019intero iter di connessione.<\/p>\n<p>L\u2019offerta &#8222;chiavi in mano&#8220;  prevede inoltre il supporto del Distributore di rete locale per gli adempimenti legati all&#8217;ottenimento degli eventuali incentivi applicabili e pi\u00f9 specificatamente le attivit\u00e0 di:<\/p>\n<ul>\n<li>registrazione per operare in nome e conto del cliente sui portali internet del GSE (c.d. Portale applicativi e Portale Web Scambio Sul Posto) ai fini della finalizzazione della procedura per l\u2019ottenimento dello Scambio sul Posto;<\/li>\n<li>invio da parte del Distributore di rete locale al cliente del cosiddetto \u201cbonifico parlante\u201d unitamente alla documentazione utile che il cliente in autonomia utilizzer\u00e0 per richiedere la detrazione fiscale.<\/li>\n<li>Per la stipula della convenzione dello Scambio sul posto \u00e8 necessario che il Cliente sia titolare del POD e della fornitura di energia elettrica. In caso contrario, sar\u00e0 necessario effettuare preventivamente la voltura pena l\u2019impossibilit\u00e0 di accesso all&#8217;incentivo.<\/li>\n<\/ul>\n<p>Ref. 4.5kW-SMART-POLY-ESS9.6<br \/>\n(Valida solo per il mercato italiano\/Available for Italian market only)<br \/>\n\r\n\t\t<div class=\"divider4\"><span><\/span><\/div>\r\n\t\t<\/p>\n<h2>Downloads<\/h2>\n<p><a href=\"https:\/\/seasolargroup.com\/wp-content\/uploads\/2018\/06\/Canadian_Solar-Datasheet-SuperPower_CS6K-P_v5.562_EN.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">Canadian Solar Datasheet SuperPower CS6K-P v5.562_EN<\/a><br \/>\n&nbsp;<br \/>\n<a href=\"https:\/\/seasolargroup.com\/wp-content\/uploads\/2018\/06\/Hanwha_Q_CELLS_Data_sheet_QPLUS_BFR-G4.1_275-285_2017-05_Rev02_EN.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">Hanwha Q-CELLS Datasheet QPLUS_BFR-G4.1_275-285_2017-05_Rev02_EN<\/a><br \/>\n&nbsp;<br \/>\n<a href=\"https:\/\/seasolargroup.com\/wp-content\/uploads\/2018\/06\/JAP6-60-260-280-4BB-RE.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">JA SOLAR JAP6 60 260-280-4BB-RE<\/a><br \/>\n&nbsp;<br \/>\n<a href=\"https:\/\/seasolargroup.com\/wp-content\/uploads\/2018\/06\/EN-Eagle-60PP-260-280W_20.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">Jinko Solar Eagle 60PP 260-280W_20<\/a><br \/>\n&nbsp;<br \/>\n<a href=\"https:\/\/seasolargroup.com\/wp-content\/uploads\/2018\/06\/EN_TSM_PD05_datasheet_B_2017_web.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">Trina Solar TSM-PD05 datasheet_B_2017_web<\/a><br \/>\n&nbsp;<br \/>\n<a href=\"https:\/\/seasolargroup.com\/wp-content\/uploads\/2018\/08\/GoodWE-product-flyer_EM.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">GoodWE product flyer_EM<\/a><br \/>\n&nbsp;<br \/>\n<a href=\"https:\/\/seasolargroup.com\/wp-content\/uploads\/2018\/08\/LowVoltageSystemSpec.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">PYLON Low+Voltage+System+Spec<\/a><br \/>\n\r\n\t\t<div class=\"divider4\"><span><\/span><\/div>\r\n\t\t<\/p>\n<h2>Related products<\/h2>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-id=\"2703\"  src=\"https:\/\/i0.wp.com\/seasolargroup.com\/wp-content\/uploads\/2018\/06\/AEG_poly_60_cells-207x300.png?resize=207%2C300&#038;ssl=1\" alt=\"\" width=\"207\" height=\"300\" class=\"alignleft size-medium wp-image-2703\" \/><br \/>\n<a href=\"https:\/\/seasolargroup.com\/product\/canadian-solar-cs6k-270p\/\">Canadian Solar cs6k-270p<\/a><br \/>\n&nbsp;<br \/>\n<a href=\"https:\/\/seasolargroup.com\/product\/hanwha-q-cells-q-plus-bfr-g4-1-280\/\">Hanwha Q-cells q-plus-bfr-g4-1-280<\/a><br \/>\n&nbsp;<br \/>\n<a href=\"https:\/\/seasolargroup.com\/product\/ja-solar-jap6-k-60-275-4bb-re\/\">JA SOLAR jap6-k-60-275-4bb-re<\/a><br \/>\n&nbsp;<br \/>\n<a href=\"https:\/\/seasolargroup.com\/product\/jinko-solar-jkm-275pp-60b\/\">Jinko Solar jkm-275pp-60b<\/a><br \/>\n&nbsp;<br \/>\n<a href=\"https:\/\/seasolargroup.com\/product\/trina-solar-honey-tsm-pd05-275\/\">Trina Solar honey-tsm-pd05<\/a><br \/>\n&nbsp;<br \/>\n&nbsp;<br \/>\n&nbsp;<br \/>\n&nbsp;<br \/>\n<img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignleft size-thumbnail wp-image-3791\" src=\"https:\/\/i0.wp.com\/seasolargroup.com\/wp-content\/uploads\/2018\/08\/5a3a33abc104f-150x150.png?resize=150%2C150&#038;ssl=1\" alt=\"\" width=\"150\" height=\"150\" data-id=\"3791\" \/><br \/>\n&nbsp;<br \/>\n<a href=\"https:\/\/seasolargroup.com\/product\/goodwe-gw3648-em\/\">GOODWE GW3648-EM<\/a><br \/>\n&nbsp;<br \/>\n&nbsp;<br \/>\n&nbsp;<br \/>\n&nbsp;<br \/>\n<img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-id=\"4358\"  src=\"https:\/\/i0.wp.com\/seasolargroup.com\/wp-content\/uploads\/2018\/08\/4xPYLON-USB2000BPLUS-300x218.jpg?resize=300%2C218&#038;ssl=1\" alt=\"\" width=\"300\" height=\"218\" class=\"alignleft size-medium wp-image-4358\" \/><br \/>\n&nbsp;<br \/>\n<a href=\"https:\/\/seasolargroup.com\/product\/4xpylon-us2000b-plus-rack-9u-kit\/\">4xPYLON US2000B-PLUS-Rack 9U-Kit<\/a><br \/>\n\r\n\t\t<div class=\"divider4\"><span><\/span><\/div>\r\n\t\t<\/p>\n<h2>Related projects<\/h2>\n<p><br \/>\n\r\n\t\t<div class=\"divider4\"><span><\/span><\/div>\r\n\t\t<\/p>\n<h2>Contact<\/h2>\n<p>Please contact us with any questions you might have related to our offers or our products. We look forward to hearing how we can make the difference to you<br \/>\n&nbsp;<br \/>\nVi preghiamo di contattarci per eventuali domande relative alle nostre offerte o ai nostri prodotti. Non vediamo l&#8217;ora di sentire come possiamo fare la differenza per voi<br \/>\n&nbsp;<br \/>\nBitte kontaktieren Sie uns, wenn Sie Fragen zu unseren Angeboten oder unseren Produkten haben. Wir freuen uns zu h\u00f6ren, wie wir den Unterschied f\u00fcr Sie machen k\u00f6nnen<br \/>\n&nbsp;<br \/>\nN&#8217;h\u00e9sitez pas \u00e0 nous contacter pour toute question concernant nos offres ou nos produits. Nous avons h\u00e2te d&#8217;entendre comment nous pouvons faire la diff\u00e9rence pour vous<br \/>\n&nbsp;<br \/>\nPor favor cont\u00e1ctenos con cualquier pregunta que pueda tener relacionada con nuestras ofertas o nuestros productos. Esperamos escuchar c\u00f3mo podemos marcar la diferencia para usted.<br \/>\n&nbsp;<br \/>\n\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f391-o1\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"391\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/de\/wp-json\/wp\/v2\/posts\/514#wpcf7-f391-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"391\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.5\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f391-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<p><label> <\/label>\n<\/p>\n<h2>Kontakt\n<\/h2>\n<p>&nbsp;<br \/>\n<label> Bitte kontaktieren Sie uns, wenn Sie Fragen zu unseren Angeboten oder unseren Produkten haben <\/label>\n<\/p>\n<p><label> Schreiben Sie an <a href=\"mailto:info@seasolar.ch\">info@seasolar.ch<\/a> oder f\u00fcllen Sie das folgende Formular aus und wir werden Sie kontaktieren: <\/label>\n<\/p>\n<p><label> Name *<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span><\/label>\n<\/p>\n<p><label> Telefonnummer *<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"tel-826\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-tel\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"tel\" name=\"tel-826\" \/><\/span><\/label>\n<\/p>\n<p><label> Deine E-Mail *<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span><\/label>\n<\/p>\n<p><label> Thema *<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-subject\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-subject\" \/><\/span> <\/label>\n<\/p>\n<p><label> Nachricht *<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" name=\"your-message\"><\/textarea><\/span> <\/label>\n<\/p>\n<p><label> * Pflichtfeld <\/label>\n<\/p>\n<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"SENDEN\" \/>\n<\/p>\n<p><label><\/label>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n<br \/>\n&nbsp;<\/p>\n<!-- sktbuilder starter --><script type=\"text\/javascript\" src=\"https:\/\/seasolar.ch\/wp-content\/plugins\/skt-builder\/sktbuilder\/sktbuilder-frontend-starter.js\"><\/script><script type=\"text\/javascript\" src=\"https:\/\/seasolar.ch\/wp-content\/plugins\/skt-builder\/sktbuilder-wordpress-driver.js\"><\/script><script type=\"text\/javascript\"> var starter = new SktbuilderStarter({\"mode\": \"prod\", \"skip\":[\"jquery\",\"underscore\",\"backbone\"],\"sktbuilderUrl\": \"https:\/\/seasolar.ch\/wp-content\/plugins\/skt-builder\/sktbuilder\/\", \"driver\": new SktbuilderWordpressDriver({\"ajaxUrl\": \"https:\/\/seasolar.ch\/wp-admin\/admin-ajax.php\", \"iframeUrl\": \"https:\/\/seasolar.ch\/de\/offerta-impianto-fotovoltaico-con-accumulo-chiavi-in-mano-4-5kw-smart-poly-ess-9-6\/?sktbuilder=true\", \"pageId\": 514,  \"nonce\": \"b7bccc9063\", \"pages\": [], \"page\": \"Offerta Impianto fotovoltaico con accumulo chiavi in mano 4.5kW SMART POLY ESS 9.6\" }) });<\/script><!-- end sktbuilder starter -->","protected":false},"excerpt":{"rendered":"<p>Offerta Impianto fotovoltaico con accumulo &#8222;chiavi in mano&#8220; 4.5kW SMART POLY ESS 9.6 Prezzo su richiesta Seasolar offre la possibilit\u00e0 di scegliere quattro linee di offerta chiavi in mano (BASIC, SMART, PREMIUM, ULTRA) con la garanzia del miglior servizio di installazione eseguito da tecnici specializzati per il massimo dell\u2019efficienza e della sicurezza: tutti gli impianti<br \/><a class=\"moretag\" href=\"https:\/\/seasolar.ch\/de\/offerta-impianto-fotovoltaico-con-accumulo-chiavi-in-mano-4-5kw-smart-poly-ess-9-6\/\">+ Read More<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[26,25,118],"tags":[65,66,67,68,69,70,71,72,73,74,75,76,77,78,79,80,81,82,83,84,85,86,87,88,89,90,91,92,93,94,95,96,97,98,99,100,101,109,102,103,104,105,106,107],"class_list":["post-514","post","type-post","status-publish","format-standard","hentry","category-offer-residential-pv-system","category-offers","category-power-5kw","tag-costi-fotovoltaico-con-accumulo","tag-costi-fotovoltaico-con-batterie","tag-costi-impianti-fotovoltaici-con-accumulo","tag-costi-impianti-fotovoltaici-con-batterie","tag-costo-fotovoltaico-con-accumulo","tag-costo-fotovoltaico-con-batterie","tag-costo-impianto-fotovoltaico-con-accumulo","tag-costo-impianto-fotovoltaico-con-batterie","tag-fotovoltaico-con-accumulo","tag-fotovoltaico-con-batterie","tag-goodwe","tag-impianti-fotovoltaici-con-accumulo","tag-impianti-fotovoltaici-con-batterie","tag-impianto-fotovoltaico-con-accumulo","tag-impianto-fotovoltaico-con-batterie","tag-offerte-fotovoltaico-con-accumulo","tag-offerte-fotovoltaico-con-batterie","tag-offerte-impianti-fotovoltaici-con-accumulo","tag-offerte-impianti-fotovoltaici-con-batterie","tag-offerte-impianto-fotovoltaico-con-accumulo","tag-offerte-impianto-fotovoltaico-con-batterie","tag-preventivi-fotovoltaico-con-accumulo","tag-preventivi-fotovoltaico-con-batterie","tag-preventivi-impianti-fotovoltaici-con-accumulo","tag-preventivi-impianti-fotovoltaici-con-batterie","tag-preventivo-fotovoltaico-con-accumulo","tag-preventivo-fotovoltaico-con-batterie","tag-preventivo-impianto-fotovoltaico-con-accumulo","tag-preventivo-impianto-fotovoltaico-con-batterie","tag-prezzi-fotovoltaico-con-accumulo","tag-prezzi-fotovoltaico-con-batterie","tag-prezzi-impianti-fotovoltaici-con-accumulo","tag-prezzi-impianti-fotovoltaici-con-batterie","tag-prezzo-fotovoltaico-con-accumulo","tag-prezzo-fotovoltaico-con-batterie","tag-prezzo-impianto-fotovoltaico-con-accumulo","tag-prezzo-impianto-fotovoltaico-con-batterie","tag-pylon","tag-vendita-fotovoltaico-con-accumulo","tag-vendita-fotovoltaico-con-batterie","tag-vendita-impianti-fotovoltaici-con-accumulo","tag-vendita-impianti-fotovoltaici-con-batterie","tag-vendita-impianto-fotovoltaico-con-accumulo","tag-vendita-impianto-fotovoltaico-con-batterie"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Offerta Impianto fotovoltaico con accumulo chiavi in mano 4.5kW SMART POLY ESS 9.6 - Seasolar Swiss<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/seasolar.ch\/offerta-impianto-fotovoltaico-con-accumulo-chiavi-in-mano-4-5kw-smart-poly-ess-9-6\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Offerta Impianto fotovoltaico con accumulo chiavi in mano 4.5kW SMART POLY ESS 9.6\" \/>\n<meta property=\"og:description\" content=\"Offerta Impianto fotovoltaico con accumulo &#8222;chiavi in mano&#8220; 4.5kW SMART POLY ESS 9.6 Prezzo su richiesta Seasolar offre la possibilit\u00e0 di scegliere quattro linee di offerta chiavi in mano (BASIC, SMART, PREMIUM, ULTRA) con la garanzia del miglior servizio di installazione eseguito da tecnici specializzati per il massimo dell\u2019efficienza e della sicurezza: tutti gli impianti+ Read More\" \/>\n<meta property=\"og:url\" content=\"https:\/\/seasolar.ch\/offerta-impianto-fotovoltaico-con-accumulo-chiavi-in-mano-4-5kw-smart-poly-ess-9-6\/\" \/>\n<meta property=\"og:site_name\" content=\"Seasolar Swiss\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/seasolargroup\" \/>\n<meta property=\"article:published_time\" content=\"2019-01-17T23:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/seasolar.ch\/wp-content\/uploads\/2025\/09\/PYLON-USB2000BPLUS-2.jpg?fit=670%2C400&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"670\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Seasolar Swiss\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@seasolargroup\" \/>\n<meta name=\"twitter:site\" content=\"@seasolargroup\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Seasolar Swiss\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/seasolar.ch\\\/offerta-impianto-fotovoltaico-con-accumulo-chiavi-in-mano-4-5kw-smart-poly-ess-9-6\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/seasolar.ch\\\/offerta-impianto-fotovoltaico-con-accumulo-chiavi-in-mano-4-5kw-smart-poly-ess-9-6\\\/\"},\"author\":{\"name\":\"Seasolar Swiss\",\"@id\":\"https:\\\/\\\/seasolar.ch\\\/#\\\/schema\\\/person\\\/6ff7cd8c09e51bbd963d0fd0a933945d\"},\"headline\":\"Offerta Impianto fotovoltaico con accumulo chiavi in mano 4.5kW SMART POLY ESS 9.6\",\"datePublished\":\"2019-01-17T23:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/seasolar.ch\\\/offerta-impianto-fotovoltaico-con-accumulo-chiavi-in-mano-4-5kw-smart-poly-ess-9-6\\\/\"},\"wordCount\":867,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/seasolar.ch\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/seasolar.ch\\\/offerta-impianto-fotovoltaico-con-accumulo-chiavi-in-mano-4-5kw-smart-poly-ess-9-6\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/seasolargroup.com\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/AEG_poly_60_cells-207x300.png\",\"keywords\":[\"costi fotovoltaico con accumulo\",\"costi fotovoltaico con batterie\",\"costi impianti fotovoltaici con accumulo\",\"costi impianti fotovoltaici con batterie\",\"costo fotovoltaico con accumulo\",\"costo fotovoltaico con batterie\",\"costo impianto fotovoltaico con accumulo\",\"costo impianto fotovoltaico con batterie\",\"fotovoltaico con accumulo\",\"fotovoltaico con batterie\",\"GOODWE\",\"impianti fotovoltaici con accumulo\",\"impianti fotovoltaici con batterie\",\"impianto fotovoltaico con accumulo\",\"impianto fotovoltaico con batterie\",\"offerte fotovoltaico con accumulo\",\"offerte fotovoltaico con batterie\",\"offerte impianti fotovoltaici con accumulo\",\"offerte impianti fotovoltaici con batterie\",\"offerte impianto fotovoltaico con accumulo\",\"offerte impianto fotovoltaico con batterie\",\"preventivi fotovoltaico con accumulo\",\"preventivi fotovoltaico con batterie\",\"preventivi impianti fotovoltaici con accumulo\",\"preventivi impianti fotovoltaici con batterie\",\"preventivo fotovoltaico con accumulo\",\"preventivo fotovoltaico con batterie\",\"preventivo impianto fotovoltaico con accumulo\",\"preventivo impianto fotovoltaico con batterie\",\"prezzi fotovoltaico con accumulo\",\"prezzi fotovoltaico con batterie\",\"prezzi impianti fotovoltaici con accumulo\",\"prezzi impianti fotovoltaici con batterie\",\"prezzo fotovoltaico con accumulo\",\"prezzo fotovoltaico con batterie\",\"prezzo impianto fotovoltaico con accumulo\",\"prezzo impianto fotovoltaico con batterie\",\"PYLON\",\"vendita fotovoltaico con accumulo\",\"vendita fotovoltaico con batterie\",\"vendita impianti fotovoltaici con accumulo\",\"vendita impianti fotovoltaici con batterie\",\"vendita impianto fotovoltaico con accumulo\",\"vendita impianto fotovoltaico con batterie\"],\"articleSection\":[\"Angebot private Photovoltaikanlage\",\"Angebote\",\"Power 5kW\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/seasolar.ch\\\/offerta-impianto-fotovoltaico-con-accumulo-chiavi-in-mano-4-5kw-smart-poly-ess-9-6\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/seasolar.ch\\\/offerta-impianto-fotovoltaico-con-accumulo-chiavi-in-mano-4-5kw-smart-poly-ess-9-6\\\/\",\"url\":\"https:\\\/\\\/seasolar.ch\\\/offerta-impianto-fotovoltaico-con-accumulo-chiavi-in-mano-4-5kw-smart-poly-ess-9-6\\\/\",\"name\":\"Offerta Impianto fotovoltaico con accumulo chiavi in mano 4.5kW SMART POLY ESS 9.6 - Seasolar Swiss\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/seasolar.ch\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/seasolar.ch\\\/offerta-impianto-fotovoltaico-con-accumulo-chiavi-in-mano-4-5kw-smart-poly-ess-9-6\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/seasolar.ch\\\/offerta-impianto-fotovoltaico-con-accumulo-chiavi-in-mano-4-5kw-smart-poly-ess-9-6\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/seasolargroup.com\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/AEG_poly_60_cells-207x300.png\",\"datePublished\":\"2019-01-17T23:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/seasolar.ch\\\/offerta-impianto-fotovoltaico-con-accumulo-chiavi-in-mano-4-5kw-smart-poly-ess-9-6\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/seasolar.ch\\\/offerta-impianto-fotovoltaico-con-accumulo-chiavi-in-mano-4-5kw-smart-poly-ess-9-6\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/seasolar.ch\\\/offerta-impianto-fotovoltaico-con-accumulo-chiavi-in-mano-4-5kw-smart-poly-ess-9-6\\\/#primaryimage\",\"url\":\"https:\\\/\\\/seasolargroup.com\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/AEG_poly_60_cells-207x300.png\",\"contentUrl\":\"https:\\\/\\\/seasolargroup.com\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/AEG_poly_60_cells-207x300.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/seasolar.ch\\\/offerta-impianto-fotovoltaico-con-accumulo-chiavi-in-mano-4-5kw-smart-poly-ess-9-6\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/seasolar.ch\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Offerta Impianto fotovoltaico con accumulo chiavi in mano 4.5kW SMART POLY ESS 9.6\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/seasolar.ch\\\/#website\",\"url\":\"https:\\\/\\\/seasolar.ch\\\/\",\"name\":\"Seasolar Swiss\",\"description\":\"Dal 2008 impianti fotovoltaici &quot;chiavi in mano&quot;\",\"publisher\":{\"@id\":\"https:\\\/\\\/seasolar.ch\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/seasolar.ch\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/seasolar.ch\\\/#organization\",\"name\":\"Seasolar Swiss\",\"url\":\"https:\\\/\\\/seasolar.ch\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/seasolar.ch\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/seasolar.ch\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/cropped-seasolar_logo_2024_social.png\",\"contentUrl\":\"https:\\\/\\\/seasolar.ch\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/cropped-seasolar_logo_2024_social.png\",\"width\":512,\"height\":512,\"caption\":\"Seasolar Swiss\"},\"image\":{\"@id\":\"https:\\\/\\\/seasolar.ch\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/seasolargroup\",\"https:\\\/\\\/x.com\\\/seasolargroup\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/seasolar-group-news\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCVrmhrGih_bFnpj0as_vDuQ\",\"https:\\\/\\\/www.instagram.com\\\/fotovoltaico_seasolar\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/seasolar.ch\\\/#\\\/schema\\\/person\\\/6ff7cd8c09e51bbd963d0fd0a933945d\",\"name\":\"Seasolar Swiss\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ea12c6ae3ba2d3c3a39d1e66beb67868a738b85d04b9d89fdd142f88a6dab475?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ea12c6ae3ba2d3c3a39d1e66beb67868a738b85d04b9d89fdd142f88a6dab475?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ea12c6ae3ba2d3c3a39d1e66beb67868a738b85d04b9d89fdd142f88a6dab475?s=96&d=mm&r=g\",\"caption\":\"Seasolar Swiss\"},\"sameAs\":[\"https:\\\/\\\/seasolar.ch\"],\"url\":\"https:\\\/\\\/seasolar.ch\\\/de\\\/author\\\/seasolarswiss\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Offerta Impianto fotovoltaico con accumulo chiavi in mano 4.5kW SMART POLY ESS 9.6 - Seasolar Swiss","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/seasolar.ch\/offerta-impianto-fotovoltaico-con-accumulo-chiavi-in-mano-4-5kw-smart-poly-ess-9-6\/","og_locale":"de_DE","og_type":"article","og_title":"Offerta Impianto fotovoltaico con accumulo chiavi in mano 4.5kW SMART POLY ESS 9.6","og_description":"Offerta Impianto fotovoltaico con accumulo &#8222;chiavi in mano&#8220; 4.5kW SMART POLY ESS 9.6 Prezzo su richiesta Seasolar offre la possibilit\u00e0 di scegliere quattro linee di offerta chiavi in mano (BASIC, SMART, PREMIUM, ULTRA) con la garanzia del miglior servizio di installazione eseguito da tecnici specializzati per il massimo dell\u2019efficienza e della sicurezza: tutti gli impianti+ Read More","og_url":"https:\/\/seasolar.ch\/offerta-impianto-fotovoltaico-con-accumulo-chiavi-in-mano-4-5kw-smart-poly-ess-9-6\/","og_site_name":"Seasolar Swiss","article_publisher":"https:\/\/www.facebook.com\/seasolargroup","article_published_time":"2019-01-17T23:00:00+00:00","og_image":[{"width":670,"height":400,"url":"https:\/\/i0.wp.com\/seasolar.ch\/wp-content\/uploads\/2025\/09\/PYLON-USB2000BPLUS-2.jpg?fit=670%2C400&ssl=1","type":"image\/jpeg"}],"author":"Seasolar Swiss","twitter_card":"summary_large_image","twitter_creator":"@seasolargroup","twitter_site":"@seasolargroup","twitter_misc":{"Verfasst von":"Seasolar Swiss","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/seasolar.ch\/offerta-impianto-fotovoltaico-con-accumulo-chiavi-in-mano-4-5kw-smart-poly-ess-9-6\/#article","isPartOf":{"@id":"https:\/\/seasolar.ch\/offerta-impianto-fotovoltaico-con-accumulo-chiavi-in-mano-4-5kw-smart-poly-ess-9-6\/"},"author":{"name":"Seasolar Swiss","@id":"https:\/\/seasolar.ch\/#\/schema\/person\/6ff7cd8c09e51bbd963d0fd0a933945d"},"headline":"Offerta Impianto fotovoltaico con accumulo chiavi in mano 4.5kW SMART POLY ESS 9.6","datePublished":"2019-01-17T23:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/seasolar.ch\/offerta-impianto-fotovoltaico-con-accumulo-chiavi-in-mano-4-5kw-smart-poly-ess-9-6\/"},"wordCount":867,"commentCount":0,"publisher":{"@id":"https:\/\/seasolar.ch\/#organization"},"image":{"@id":"https:\/\/seasolar.ch\/offerta-impianto-fotovoltaico-con-accumulo-chiavi-in-mano-4-5kw-smart-poly-ess-9-6\/#primaryimage"},"thumbnailUrl":"https:\/\/seasolargroup.com\/wp-content\/uploads\/2018\/06\/AEG_poly_60_cells-207x300.png","keywords":["costi fotovoltaico con accumulo","costi fotovoltaico con batterie","costi impianti fotovoltaici con accumulo","costi impianti fotovoltaici con batterie","costo fotovoltaico con accumulo","costo fotovoltaico con batterie","costo impianto fotovoltaico con accumulo","costo impianto fotovoltaico con batterie","fotovoltaico con accumulo","fotovoltaico con batterie","GOODWE","impianti fotovoltaici con accumulo","impianti fotovoltaici con batterie","impianto fotovoltaico con accumulo","impianto fotovoltaico con batterie","offerte fotovoltaico con accumulo","offerte fotovoltaico con batterie","offerte impianti fotovoltaici con accumulo","offerte impianti fotovoltaici con batterie","offerte impianto fotovoltaico con accumulo","offerte impianto fotovoltaico con batterie","preventivi fotovoltaico con accumulo","preventivi fotovoltaico con batterie","preventivi impianti fotovoltaici con accumulo","preventivi impianti fotovoltaici con batterie","preventivo fotovoltaico con accumulo","preventivo fotovoltaico con batterie","preventivo impianto fotovoltaico con accumulo","preventivo impianto fotovoltaico con batterie","prezzi fotovoltaico con accumulo","prezzi fotovoltaico con batterie","prezzi impianti fotovoltaici con accumulo","prezzi impianti fotovoltaici con batterie","prezzo fotovoltaico con accumulo","prezzo fotovoltaico con batterie","prezzo impianto fotovoltaico con accumulo","prezzo impianto fotovoltaico con batterie","PYLON","vendita fotovoltaico con accumulo","vendita fotovoltaico con batterie","vendita impianti fotovoltaici con accumulo","vendita impianti fotovoltaici con batterie","vendita impianto fotovoltaico con accumulo","vendita impianto fotovoltaico con batterie"],"articleSection":["Angebot private Photovoltaikanlage","Angebote","Power 5kW"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/seasolar.ch\/offerta-impianto-fotovoltaico-con-accumulo-chiavi-in-mano-4-5kw-smart-poly-ess-9-6\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/seasolar.ch\/offerta-impianto-fotovoltaico-con-accumulo-chiavi-in-mano-4-5kw-smart-poly-ess-9-6\/","url":"https:\/\/seasolar.ch\/offerta-impianto-fotovoltaico-con-accumulo-chiavi-in-mano-4-5kw-smart-poly-ess-9-6\/","name":"Offerta Impianto fotovoltaico con accumulo chiavi in mano 4.5kW SMART POLY ESS 9.6 - Seasolar Swiss","isPartOf":{"@id":"https:\/\/seasolar.ch\/#website"},"primaryImageOfPage":{"@id":"https:\/\/seasolar.ch\/offerta-impianto-fotovoltaico-con-accumulo-chiavi-in-mano-4-5kw-smart-poly-ess-9-6\/#primaryimage"},"image":{"@id":"https:\/\/seasolar.ch\/offerta-impianto-fotovoltaico-con-accumulo-chiavi-in-mano-4-5kw-smart-poly-ess-9-6\/#primaryimage"},"thumbnailUrl":"https:\/\/seasolargroup.com\/wp-content\/uploads\/2018\/06\/AEG_poly_60_cells-207x300.png","datePublished":"2019-01-17T23:00:00+00:00","breadcrumb":{"@id":"https:\/\/seasolar.ch\/offerta-impianto-fotovoltaico-con-accumulo-chiavi-in-mano-4-5kw-smart-poly-ess-9-6\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/seasolar.ch\/offerta-impianto-fotovoltaico-con-accumulo-chiavi-in-mano-4-5kw-smart-poly-ess-9-6\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/seasolar.ch\/offerta-impianto-fotovoltaico-con-accumulo-chiavi-in-mano-4-5kw-smart-poly-ess-9-6\/#primaryimage","url":"https:\/\/seasolargroup.com\/wp-content\/uploads\/2018\/06\/AEG_poly_60_cells-207x300.png","contentUrl":"https:\/\/seasolargroup.com\/wp-content\/uploads\/2018\/06\/AEG_poly_60_cells-207x300.png"},{"@type":"BreadcrumbList","@id":"https:\/\/seasolar.ch\/offerta-impianto-fotovoltaico-con-accumulo-chiavi-in-mano-4-5kw-smart-poly-ess-9-6\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/seasolar.ch\/"},{"@type":"ListItem","position":2,"name":"Offerta Impianto fotovoltaico con accumulo chiavi in mano 4.5kW SMART POLY ESS 9.6"}]},{"@type":"WebSite","@id":"https:\/\/seasolar.ch\/#website","url":"https:\/\/seasolar.ch\/","name":"Seasolar Swiss","description":"Dal 2008 impianti fotovoltaici &quot;chiavi in mano&quot;","publisher":{"@id":"https:\/\/seasolar.ch\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/seasolar.ch\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/seasolar.ch\/#organization","name":"Seasolar Swiss","url":"https:\/\/seasolar.ch\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/seasolar.ch\/#\/schema\/logo\/image\/","url":"https:\/\/seasolar.ch\/wp-content\/uploads\/2025\/08\/cropped-seasolar_logo_2024_social.png","contentUrl":"https:\/\/seasolar.ch\/wp-content\/uploads\/2025\/08\/cropped-seasolar_logo_2024_social.png","width":512,"height":512,"caption":"Seasolar Swiss"},"image":{"@id":"https:\/\/seasolar.ch\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/seasolargroup","https:\/\/x.com\/seasolargroup","https:\/\/www.linkedin.com\/in\/seasolar-group-news\/","https:\/\/www.youtube.com\/channel\/UCVrmhrGih_bFnpj0as_vDuQ","https:\/\/www.instagram.com\/fotovoltaico_seasolar\/"]},{"@type":"Person","@id":"https:\/\/seasolar.ch\/#\/schema\/person\/6ff7cd8c09e51bbd963d0fd0a933945d","name":"Seasolar Swiss","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/ea12c6ae3ba2d3c3a39d1e66beb67868a738b85d04b9d89fdd142f88a6dab475?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ea12c6ae3ba2d3c3a39d1e66beb67868a738b85d04b9d89fdd142f88a6dab475?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ea12c6ae3ba2d3c3a39d1e66beb67868a738b85d04b9d89fdd142f88a6dab475?s=96&d=mm&r=g","caption":"Seasolar Swiss"},"sameAs":["https:\/\/seasolar.ch"],"url":"https:\/\/seasolar.ch\/de\/author\/seasolarswiss\/"}]}},"jetpack_featured_media_url":"","jetpack_likes_enabled":true,"jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/seasolar.ch\/de\/wp-json\/wp\/v2\/posts\/514","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/seasolar.ch\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/seasolar.ch\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/seasolar.ch\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/seasolar.ch\/de\/wp-json\/wp\/v2\/comments?post=514"}],"version-history":[{"count":0,"href":"https:\/\/seasolar.ch\/de\/wp-json\/wp\/v2\/posts\/514\/revisions"}],"wp:attachment":[{"href":"https:\/\/seasolar.ch\/de\/wp-json\/wp\/v2\/media?parent=514"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/seasolar.ch\/de\/wp-json\/wp\/v2\/categories?post=514"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/seasolar.ch\/de\/wp-json\/wp\/v2\/tags?post=514"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}