{"id":2498,"date":"2024-02-05T00:00:00","date_gmt":"2024-02-04T23:00:00","guid":{"rendered":"https:\/\/seasolar.ch\/portfolio\/fotovoltaico-10kw-cagliari-it-09011\/"},"modified":"2024-02-05T00:00:00","modified_gmt":"2024-02-04T23:00:00","slug":"fotovoltaico-10kw-cagliari-it-09011","status":"publish","type":"jetpack-portfolio","link":"https:\/\/seasolar.ch\/es\/portfolio\/fotovoltaico-10kw-cagliari-it-09011\/","title":{"rendered":"Fotovoltaico 10kW Cagliari IT-09011"},"content":{"rendered":"<p><br \/>\n&nbsp;<br \/>\nImpianto Fotovoltaico \u00abchiavi in mano\u00bb 10kW Cagliari IT-09011<\/p>\n<ul>\n<li>Potenza 10kW<\/li>\n<li>Moduli fotovoltaici in silicio monocristallino Q-CELLS<\/li>\n<li>Inverter GOODWE<\/li>\n<li>Strutture di sostegno per installazione su copertura a falda inclinata<\/li>\n<li>Quadro di campo<\/li>\n<li>Quadro generale conforme alla normativa italiana CEI 0-21<\/li>\n<\/ul>\n<p>Seasolar offre un servizio completo \u201cchiavi in mano\u201d al privato o l\u2019impresa che desidera realizzare un impianto fotovoltaico sul proprio edificio, a parziale o totale copertura del proprio fabbisogno energetico.<\/p>\n<p>Il servizio \u00abchiavi in mano\u00bb include:<\/p>\n<ul>\n<li>Sopralluogo sul sito di installazione<\/li>\n<li>Relazione di fattibilit\u00e0 tecnica ed economica (business plan)<\/li>\n<li>Progetto esecutivo<\/li>\n<li>Istruzione ed inoltro richiesta di connessione di rete al Gestore competente<\/li>\n<li>Predisposizione Piano delle misure per la sicurezza fisica e l&#8217;integrit\u00e0 dei lavoratori<\/li>\n<li>Istruzione ed inoltro richiesta di convenzione al Gestore dei Servizi Energetici<\/li>\n<li>Consegna documentazione tecnica per la denuncia di apertura officina elettrica<\/li>\n<\/ul>\n<p>Il servizio pu\u00f2 includere anche:<\/p>\n<ul>\n<li>Piano di manutenzione ordinaria annuale dell&#8217;impianto<\/li>\n<li>Monitoraggio e gestione da remoto dell&#8217;impianto<\/li>\n<li>Pronto intervento guasti in 24\/48ore<\/li>\n<li>Pulizia dell&#8217;impianto<\/li>\n<\/ul>\n<p>Progettiamo e installiamo impianti fotovoltaici con l\u2019obiettivo di ridurre o azzerare il fabbisogno energetico dell\u2019immobile utilizzando prodotti di alta qualit\u00e0 scelti grazie all\u2019esperienza ultra decennale maturata nel settore.<\/p>\n<p>Proponiamo moduli fotovoltaici ad alta efficienza abbinati ai migliori inverter con oltre 20 anni di garanzia.<\/p>\n<p>Ciascuna offerta pu\u00f2 essere personalizzata attingendo al vasto e sempre aggiornato <a href=\"https:\/\/seasolargroup.com\/products\/\">catalogo prodotti<\/a> che comprende anche sistemi di accumulo, sistemi per la mobilit\u00e0 elettrica e accessori.<\/p>\n<p>Sfrutta al massimo lo spazio disponibile sul tuo tetto installando la massima potenza ottenibile con i nostri moduli fotovoltaici ad alta efficienza.<\/p>\n<p>Massimizza l&#8217;autoconsumo dell\u2019energia prodotta dal tuo impianto con i nuovi inverter dotati di sistema di accumulo.<\/p>\n<p>Tieni sotto controllo la produzione e i consumi del tuo impianto comodamente dal tuo smartphone o dal tuo PC.<br \/>\n\r\n\t\t<div class=\"divider4\"><span><\/span><\/div>\r\n\t\t<\/p>\n<h2>Prodotti<\/h2>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-8153\" src=\"https:\/\/i0.wp.com\/seasolargroup.com\/wp-content\/uploads\/2019\/12\/mono-logo-300x300.png?resize=300%2C300&#038;ssl=1\" alt=\"Fotovoltaico offerta impianto 100kW\" width=\"300\" height=\"300\" data-id=\"8153\" \/><br \/>\n<a href=\"https:\/\/seasolargroup.com\/product-tag\/q-cells\/\">Moduli fotovoltaici Q-CELLS<\/a><br \/>\n<img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-id=\"9995\"  src=\"https:\/\/i0.wp.com\/seasolargroup.com\/wp-content\/uploads\/2020\/02\/GOODWE-ET-300x300.jpg?resize=300%2C300&#038;ssl=1\" alt=\"GOODWE-ET\" width=\"300\" height=\"300\" class=\"alignnone size-medium wp-image-9995\" \/><br \/>\n<a href=\"https:\/\/seasolargroup.com\/product-tag\/goodwe\/\">Inverter GOODWE<\/a><br \/>\n\r\n\t\t<div class=\"divider4\"><span><\/span><\/div>\r\n\t\t<\/p>\n<h2>Offerte<\/h2>\n<p><a href=\"https:\/\/seasolargroup.com\/tag\/q-cells\/\">Offerte impianto fotovoltaico con moduli Q-CELLS<\/a><br \/>\n&nbsp;<br \/>\n<a href=\"https:\/\/seasolargroup.com\/tag\/goodwe\/\">Offerte impianto fotovoltaico con inverter GOODWE<\/a><br \/>\n\r\n\t\t<div class=\"divider4\"><span><\/span><\/div>\r\n\t\t<\/p>\n<h2>Video<\/h2>\n<p><span class=\"embed-youtube\" style=\"text-align:center; display: block;\"><iframe loading=\"lazy\" class=\"youtube-player\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/Hugqfbg9hH0?version=3&#038;rel=1&#038;showsearch=0&#038;showinfo=1&#038;iv_load_policy=1&#038;fs=1&#038;hl=es-ES&#038;autohide=2&#038;wmode=transparent&#038;listType=playlist&#038;list=PLwqK5bEOfjvKm1sTmdbOfbBNBU_czPbrY\" allowfullscreen=\"true\" style=\"border:0;\" sandbox=\"allow-scripts allow-same-origin allow-popups allow-presentation allow-popups-to-escape-sandbox\"><\/iframe><\/span><br \/>\n\r\n\t\t<div class=\"divider4\"><span><\/span><\/div>\r\n\t\t<br \/>\n\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f391-o1\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"391\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/es\/wp-json\/wp\/v2\/jetpack-portfolio\/2498#wpcf7-f391-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"391\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.5\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f391-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<p><label> <\/label>\n<\/p>\n<h2>Contacto\n<\/h2>\n<p>&nbsp;<br \/>\n<label> Por favor cont\u00e1ctenos con cualquier pregunta que pueda tener relacionada con nuestras ofertas o nuestros productos <\/label>\n<\/p>\n<p><label> Escriba a <a href=\"mailto:info@seasolar.ch\">info@seasolar.ch<\/a> o complete el siguiente formulario y nos pondremos en contacto con usted: <\/label>\n<\/p>\n<p><label> Nombre *<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span><\/label>\n<\/p>\n<p><label> N\u00famero de tel\u00e9fono *<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"tel-826\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-tel\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"tel\" name=\"tel-826\" \/><\/span><\/label>\n<\/p>\n<p><label> Tu correo electr\u00f3nico *<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span><\/label>\n<\/p>\n<p><label> Sujeto *<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-subject\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-subject\" \/><\/span> <\/label>\n<\/p>\n<p><label> Mensaje *<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" name=\"your-message\"><\/textarea><\/span> <\/label>\n<\/p>\n<p><label> * campo requerido <\/label>\n<\/p>\n<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"ENVIAR\" \/>\n<\/p>\n<p><label><\/label>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n<br \/>\n<span style=\"color: #ffffff;\">Fotovoltaico 10kW Cagliari IT-09011<\/span><\/p>\n<!-- sktbuilder starter --><script type=\"text\/javascript\" src=\"https:\/\/seasolar.ch\/wp-content\/plugins\/skt-builder\/sktbuilder\/sktbuilder-frontend-starter.js\"><\/script><script type=\"text\/javascript\" src=\"https:\/\/seasolar.ch\/wp-content\/plugins\/skt-builder\/sktbuilder-wordpress-driver.js\"><\/script><script type=\"text\/javascript\"> var starter = new SktbuilderStarter({\"mode\": \"prod\", \"skip\":[\"jquery\",\"underscore\",\"backbone\"],\"sktbuilderUrl\": \"https:\/\/seasolar.ch\/wp-content\/plugins\/skt-builder\/sktbuilder\/\", \"driver\": new SktbuilderWordpressDriver({\"ajaxUrl\": \"https:\/\/seasolar.ch\/wp-admin\/admin-ajax.php\", \"iframeUrl\": \"https:\/\/seasolar.ch\/es\/portfolio\/fotovoltaico-10kw-cagliari-it-09011\/?sktbuilder=true\", \"pageId\": 2498,  \"nonce\": \"b7bccc9063\", \"pages\": [], \"page\": \"Fotovoltaico 10kW Cagliari IT-09011\" }) });<\/script><!-- end sktbuilder starter -->","protected":false},"excerpt":{"rendered":"<p>&nbsp; Impianto Fotovoltaico \u00abchiavi in mano\u00bb 10kW Cagliari IT-09011 Potenza 10kW Moduli fotovoltaici in silicio monocristallino Q-CELLS Inverter GOODWE Strutture di sostegno per installazione su copertura a falda inclinata Quadro di campo Quadro generale conforme alla normativa italiana CEI 0-21 Seasolar offre un servizio completo \u201cchiavi in mano\u201d al privato o l\u2019impresa che desidera realizzare<br \/><a class=\"moretag\" href=\"https:\/\/seasolar.ch\/es\/portfolio\/fotovoltaico-10kw-cagliari-it-09011\/\">+ Read More<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","template":"","format":"standard","meta":{"footnotes":""},"jetpack-portfolio-type":[268,281],"jetpack-portfolio-tag":[270,271,297,307],"class_list":["post-2498","jetpack-portfolio","type-jetpack-portfolio","status-publish","format-standard","hentry","jetpack-portfolio-type-industrial-pv-system","jetpack-portfolio-type-power-10kw","jetpack-portfolio-tag-fotovoltaico-cagliari","jetpack-portfolio-tag-fotovoltaico-sardegna","jetpack-portfolio-tag-goodwe","jetpack-portfolio-tag-q-cells"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Fotovoltaico 10kW Cagliari IT-09011 - Seasolar Swiss<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/seasolar.ch\/portfolio\/fotovoltaico-10kw-cagliari-it-09011\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fotovoltaico 10kW Cagliari IT-09011\" \/>\n<meta property=\"og:description\" content=\"&nbsp; Impianto Fotovoltaico \u00abchiavi in mano\u00bb 10kW Cagliari IT-09011 Potenza 10kW Moduli fotovoltaici in silicio monocristallino Q-CELLS Inverter GOODWE Strutture di sostegno per installazione su copertura a falda inclinata Quadro di campo Quadro generale conforme alla normativa italiana CEI 0-21 Seasolar offre un servizio completo \u201cchiavi in mano\u201d al privato o l\u2019impresa che desidera realizzare+ Read More\" \/>\n<meta property=\"og:url\" content=\"https:\/\/seasolar.ch\/portfolio\/fotovoltaico-10kw-cagliari-it-09011\/\" \/>\n<meta property=\"og:site_name\" content=\"Seasolar Swiss\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/seasolargroup\" \/>\n<meta property=\"og:image\" content=\"https:\/\/seasolargroup.com\/wp-content\/uploads\/2019\/12\/mono-logo-300x300.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@seasolargroup\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/seasolar.ch\\\/portfolio\\\/fotovoltaico-10kw-cagliari-it-09011\\\/\",\"url\":\"https:\\\/\\\/seasolar.ch\\\/portfolio\\\/fotovoltaico-10kw-cagliari-it-09011\\\/\",\"name\":\"Fotovoltaico 10kW Cagliari IT-09011 - Seasolar Swiss\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/seasolar.ch\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/seasolar.ch\\\/portfolio\\\/fotovoltaico-10kw-cagliari-it-09011\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/seasolar.ch\\\/portfolio\\\/fotovoltaico-10kw-cagliari-it-09011\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/seasolargroup.com\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/mono-logo-300x300.png\",\"datePublished\":\"2024-02-04T23:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/seasolar.ch\\\/portfolio\\\/fotovoltaico-10kw-cagliari-it-09011\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/seasolar.ch\\\/portfolio\\\/fotovoltaico-10kw-cagliari-it-09011\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/seasolar.ch\\\/portfolio\\\/fotovoltaico-10kw-cagliari-it-09011\\\/#primaryimage\",\"url\":\"https:\\\/\\\/seasolargroup.com\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/mono-logo-300x300.png\",\"contentUrl\":\"https:\\\/\\\/seasolargroup.com\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/mono-logo-300x300.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/seasolar.ch\\\/portfolio\\\/fotovoltaico-10kw-cagliari-it-09011\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/seasolar.ch\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Progetti\",\"item\":\"https:\\\/\\\/seasolar.ch\\\/portfolio\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Fotovoltaico 10kW Cagliari IT-09011\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/seasolar.ch\\\/#website\",\"url\":\"https:\\\/\\\/seasolar.ch\\\/\",\"name\":\"Seasolar Swiss\",\"description\":\"Dal 2008 impianti fotovoltaici &quot;chiavi in mano&quot;\",\"publisher\":{\"@id\":\"https:\\\/\\\/seasolar.ch\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/seasolar.ch\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/seasolar.ch\\\/#organization\",\"name\":\"Seasolar Swiss\",\"url\":\"https:\\\/\\\/seasolar.ch\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/seasolar.ch\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/seasolar.ch\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/cropped-seasolar_logo_2024_social.png\",\"contentUrl\":\"https:\\\/\\\/seasolar.ch\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/cropped-seasolar_logo_2024_social.png\",\"width\":512,\"height\":512,\"caption\":\"Seasolar Swiss\"},\"image\":{\"@id\":\"https:\\\/\\\/seasolar.ch\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/seasolargroup\",\"https:\\\/\\\/x.com\\\/seasolargroup\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/seasolar-group-news\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCVrmhrGih_bFnpj0as_vDuQ\",\"https:\\\/\\\/www.instagram.com\\\/fotovoltaico_seasolar\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Fotovoltaico 10kW Cagliari IT-09011 - Seasolar Swiss","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/seasolar.ch\/portfolio\/fotovoltaico-10kw-cagliari-it-09011\/","og_locale":"es_ES","og_type":"article","og_title":"Fotovoltaico 10kW Cagliari IT-09011","og_description":"&nbsp; Impianto Fotovoltaico \u00abchiavi in mano\u00bb 10kW Cagliari IT-09011 Potenza 10kW Moduli fotovoltaici in silicio monocristallino Q-CELLS Inverter GOODWE Strutture di sostegno per installazione su copertura a falda inclinata Quadro di campo Quadro generale conforme alla normativa italiana CEI 0-21 Seasolar offre un servizio completo \u201cchiavi in mano\u201d al privato o l\u2019impresa che desidera realizzare+ Read More","og_url":"https:\/\/seasolar.ch\/portfolio\/fotovoltaico-10kw-cagliari-it-09011\/","og_site_name":"Seasolar Swiss","article_publisher":"https:\/\/www.facebook.com\/seasolargroup","og_image":[{"url":"https:\/\/seasolargroup.com\/wp-content\/uploads\/2019\/12\/mono-logo-300x300.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_site":"@seasolargroup","twitter_misc":{"Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/seasolar.ch\/portfolio\/fotovoltaico-10kw-cagliari-it-09011\/","url":"https:\/\/seasolar.ch\/portfolio\/fotovoltaico-10kw-cagliari-it-09011\/","name":"Fotovoltaico 10kW Cagliari IT-09011 - Seasolar Swiss","isPartOf":{"@id":"https:\/\/seasolar.ch\/#website"},"primaryImageOfPage":{"@id":"https:\/\/seasolar.ch\/portfolio\/fotovoltaico-10kw-cagliari-it-09011\/#primaryimage"},"image":{"@id":"https:\/\/seasolar.ch\/portfolio\/fotovoltaico-10kw-cagliari-it-09011\/#primaryimage"},"thumbnailUrl":"https:\/\/seasolargroup.com\/wp-content\/uploads\/2019\/12\/mono-logo-300x300.png","datePublished":"2024-02-04T23:00:00+00:00","breadcrumb":{"@id":"https:\/\/seasolar.ch\/portfolio\/fotovoltaico-10kw-cagliari-it-09011\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/seasolar.ch\/portfolio\/fotovoltaico-10kw-cagliari-it-09011\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/seasolar.ch\/portfolio\/fotovoltaico-10kw-cagliari-it-09011\/#primaryimage","url":"https:\/\/seasolargroup.com\/wp-content\/uploads\/2019\/12\/mono-logo-300x300.png","contentUrl":"https:\/\/seasolargroup.com\/wp-content\/uploads\/2019\/12\/mono-logo-300x300.png"},{"@type":"BreadcrumbList","@id":"https:\/\/seasolar.ch\/portfolio\/fotovoltaico-10kw-cagliari-it-09011\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/seasolar.ch\/"},{"@type":"ListItem","position":2,"name":"Progetti","item":"https:\/\/seasolar.ch\/portfolio\/"},{"@type":"ListItem","position":3,"name":"Fotovoltaico 10kW Cagliari IT-09011"}]},{"@type":"WebSite","@id":"https:\/\/seasolar.ch\/#website","url":"https:\/\/seasolar.ch\/","name":"Seasolar Swiss","description":"Dal 2008 impianti fotovoltaici &quot;chiavi in mano&quot;","publisher":{"@id":"https:\/\/seasolar.ch\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/seasolar.ch\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/seasolar.ch\/#organization","name":"Seasolar Swiss","url":"https:\/\/seasolar.ch\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/seasolar.ch\/#\/schema\/logo\/image\/","url":"https:\/\/seasolar.ch\/wp-content\/uploads\/2025\/08\/cropped-seasolar_logo_2024_social.png","contentUrl":"https:\/\/seasolar.ch\/wp-content\/uploads\/2025\/08\/cropped-seasolar_logo_2024_social.png","width":512,"height":512,"caption":"Seasolar Swiss"},"image":{"@id":"https:\/\/seasolar.ch\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/seasolargroup","https:\/\/x.com\/seasolargroup","https:\/\/www.linkedin.com\/in\/seasolar-group-news\/","https:\/\/www.youtube.com\/channel\/UCVrmhrGih_bFnpj0as_vDuQ","https:\/\/www.instagram.com\/fotovoltaico_seasolar\/"]}]}},"jetpack_likes_enabled":true,"jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/seasolar.ch\/es\/wp-json\/wp\/v2\/jetpack-portfolio\/2498","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/seasolar.ch\/es\/wp-json\/wp\/v2\/jetpack-portfolio"}],"about":[{"href":"https:\/\/seasolar.ch\/es\/wp-json\/wp\/v2\/types\/jetpack-portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/seasolar.ch\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/seasolar.ch\/es\/wp-json\/wp\/v2\/comments?post=2498"}],"version-history":[{"count":0,"href":"https:\/\/seasolar.ch\/es\/wp-json\/wp\/v2\/jetpack-portfolio\/2498\/revisions"}],"wp:attachment":[{"href":"https:\/\/seasolar.ch\/es\/wp-json\/wp\/v2\/media?parent=2498"}],"wp:term":[{"taxonomy":"jetpack-portfolio-type","embeddable":true,"href":"https:\/\/seasolar.ch\/es\/wp-json\/wp\/v2\/jetpack-portfolio-type?post=2498"},{"taxonomy":"jetpack-portfolio-tag","embeddable":true,"href":"https:\/\/seasolar.ch\/es\/wp-json\/wp\/v2\/jetpack-portfolio-tag?post=2498"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}