{"id":476,"date":"2018-11-07T00:00:00","date_gmt":"2018-11-06T23:00:00","guid":{"rendered":"https:\/\/seasolar.ch\/offerta-impianto-fotovoltaico-chiavi-in-mano-3kw-basic\/"},"modified":"2018-11-07T00:00:00","modified_gmt":"2018-11-06T23:00:00","slug":"offerta-impianto-fotovoltaico-chiavi-in-mano-3kw-basic","status":"publish","type":"post","link":"https:\/\/seasolar.ch\/es\/offerta-impianto-fotovoltaico-chiavi-in-mano-3kw-basic\/","title":{"rendered":"Offerta Impianto fotovoltaico chiavi in mano 3kW BASIC"},"content":{"rendered":"<p><\/p>\n<h2>Offerta Impianto fotovoltaico \u00abchiavi in mano\u00bb 3 kW BASIC<br \/>\nPrice on request<\/h2>\n<p>Seasolar offre la possibilit\u00e0 di scegliere quattro linee di offerta chiavi in mano (BASIC, SMART, PREMIUM, ULTRA) con la garanzia del miglior servizio di installazione eseguito da tecnici specializzati per il massimo dell\u2019efficienza e della sicurezza: tutti gli impianti sono garantiti per 24 mesi.<\/p>\n<p>Seasolar inoltre consente di aggiungere anche successivamente a tutti i suoi impianti il sistema di accumulo dell&#8217;energia (Energy Storage System &#8211; ESS) per massimizzare i benefici del tuo impianto fotovoltaico.<\/p>\n<p>L\u2019impianto fotovoltaico BASIC ha una potenza nominale uguale o superiore a 2,80 KWp e comprende:<\/p>\n<ul>\n<li>10 Moduli fotovoltaici in silicio policristallino a 60 celle (dim. 1650x1000x35mm.) di potenza minima 280 Wp di marca a scelta tra Amerisolar, CSun, Ecodelta\u00a0 garanzia 10 anni<\/li>\n<li>Inverter monofase con sistema di monitoraggio e WI-FI integrati, garanzia 5 anni<\/li>\n<li>Strutture di sostegno in alluminio, garanzia 10 anni.<\/li>\n<\/ul>\n<p>L\u2019installazione inclusa nel prezzo prevede:<\/p>\n<ul>\n<li>montaggio delle strutture di supporto su copertura a falda inclinata;<\/li>\n<li>predisposizione del cablaggio (vie cavo: forometrie, tubazioni, canalizzazioni);<\/li>\n<li>posa dei moduli fotovoltaici su struttura di sostegno;<\/li>\n<li>cablaggio e collegamento;<\/li>\n<li>installazione inverter;<\/li>\n<li>connessione alla rete (compresi contatti e sopralluoghi con distributore locale);<\/li>\n<li>installazione e configurazione del sistema di accumulo, ove acquistato, dei moduli batteria aggiuntivi ove acquistati, nonch\u00e9 la predisposizione dell\u2019 impianto elettrico per la funzione di back -up;<\/li>\n<li>installazione e la configurazione del sistema di monitoraggio ove acquistato;<\/li>\n<li>verifiche e collaudo;<\/li>\n<li>pulizia aree di lavoro;<\/li>\n<li>smaltimento imballaggi e rifiuti prodotti con l\u2019attivit\u00e0;<\/li>\n<li>dichiarazione di conformit\u00e0;<\/li>\n<li>oneri sicurezza.<\/li>\n<\/ul>\n<p>Per le attivit\u00e0 di gestione e smaltimento dell\u2019impianto eventualmente sostituito (RAEE), Seasolar si avvale di soggetti terzi che possiedono le caratteristiche e i requisiti obbligatori per legge per svolgere tali attivit\u00e0.<\/p>\n<p>L\u2019offerta \u00abchiavi in mano\u00bb prevede lo sviluppo progettuale dell\u2019impianto, compresa la predisposizione degli elaborati tecnici richiesti dalle autorit\u00e0 competenti per l\u2019ottenimento delle autorizzazioni necessarie alla realizzazione e all&#8217;entrata in esercizio degli impianti (ad esclusione della relazione tecnica di cui all&#8217;art. 28 L. 10\/91 s.m.i. ove richiesta).<\/p>\n<p>L\u2019offerta \u00abchiavi in mano\u00bb prevede il supporto del Distributore di rete locale per la Richiesta di Connessione dell\u2019impianto alla rete elettrica, nonch\u00e9 per l\u2019intero iter di connessione comprensivo dello scambio dei relativi documenti, inclusa la compilazione della modulistica, la predisposizione della documentazione,\u00a0nonch\u00e9 la gestione dell\u2019intero iter di connessione.<\/p>\n<p>L\u2019offerta \u00abchiavi in mano\u00bb  prevede inoltre il supporto del Distributore di rete locale per gli adempimenti legati all&#8217;ottenimento degli eventuali incentivi applicabili e pi\u00f9 specificatamente le attivit\u00e0 di:<\/p>\n<ul>\n<li>registrazione per operare in nome e conto del cliente sui portali internet del GSE (c.d. Portale applicativi e Portale Web Scambio Sul Posto) ai fini della finalizzazione della procedura per l\u2019ottenimento dello Scambio sul Posto;<\/li>\n<li>invio da parte del Distributore di rete locale al cliente del cosiddetto \u201cbonifico parlante\u201d unitamente alla documentazione utile che il cliente in autonomia utilizzer\u00e0 per richiedere la detrazione fiscale.<\/li>\n<li>Per la stipula della convenzione dello Scambio sul posto \u00e8 necessario che il Cliente sia titolare del POD e della fornitura di energia elettrica. In caso contrario, sar\u00e0 necessario effettuare preventivamente la voltura pena l\u2019impossibilit\u00e0 di accesso all&#8217;incentivo.<\/li>\n<\/ul>\n<p>Ref. 3KW-BASIC<br \/>\n(Valida solo per il mercato italiano\/Available for Italian market only)<br \/>\n\r\n\t\t<div class=\"divider4\"><span><\/span><\/div>\r\n\t\t<\/p>\n<h2>Downloads<\/h2>\n<p><a href=\"https:\/\/seasolargroup.com\/wp-content\/uploads\/2018\/06\/AS-6P30-Module-Specification.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">AMERISOLAR AS-6P30 Module Specification<\/a><br \/>\n&nbsp;<br \/>\n<a href=\"https:\/\/seasolargroup.com\/wp-content\/uploads\/2018\/06\/CSUN275-60P_Solar_Module_4BB5BB_4035_.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">CSUN 275-60P_Solar_Module_4BB5BB_4035_<\/a><br \/>\n&nbsp;<br \/>\n<a href=\"https:\/\/seasolargroup.com\/wp-content\/uploads\/2018\/06\/ECO-260P-280P.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">ECODELTA 260P-280P<\/a><br \/>\n\r\n\t\t<div class=\"divider4\"><span><\/span><\/div>\r\n\t\t<\/p>\n<h2>Related products<\/h2>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-id=\"2703\"  src=\"https:\/\/i0.wp.com\/seasolargroup.com\/wp-content\/uploads\/2018\/06\/AEG_poly_60_cells-207x300.png?resize=207%2C300&#038;ssl=1\" alt=\"\" width=\"207\" height=\"300\" class=\"alignleft size-medium wp-image-2703\" \/><br \/>\n<a href=\"https:\/\/seasolargroup.com\/product\/amerisolar-as-6p30-280\/\">Amerisolar as-6p30-280<\/a><br \/>\n&nbsp;<br \/>\n<a href=\"https:\/\/seasolargroup.com\/product\/csun-waratah-275-60p\/\">Csun waratah-275-60p<\/a><br \/>\n&nbsp;<br \/>\n<a href=\"https:\/\/seasolargroup.com\/product\/ecodelta-eco-280p\/\">Ecodelta eco-280p<\/a><br \/>\n\r\n\t\t<div class=\"divider4\"><span><\/span><\/div>\r\n\t\t<\/p>\n<h2>Related projects<\/h2>\n<p><br \/>\n\r\n\t\t<div class=\"divider4\"><span><\/span><\/div>\r\n\t\t<\/p>\n<h2>Contact<\/h2>\n<p>Please contact us with any questions you might have related to our offers or our products. We look forward to hearing how we can make the difference to you<br \/>\n&nbsp;<br \/>\nVi preghiamo di contattarci per eventuali domande relative alle nostre offerte o ai nostri prodotti. Non vediamo l&#8217;ora di sentire come possiamo fare la differenza per voi<br \/>\n&nbsp;<br \/>\nBitte kontaktieren Sie uns, wenn Sie Fragen zu unseren Angeboten oder unseren Produkten haben. Wir freuen uns zu h\u00f6ren, wie wir den Unterschied f\u00fcr Sie machen k\u00f6nnen<br \/>\n&nbsp;<br \/>\nN&#8217;h\u00e9sitez pas \u00e0 nous contacter pour toute question concernant nos offres ou nos produits. Nous avons h\u00e2te d&#8217;entendre comment nous pouvons faire la diff\u00e9rence pour vous<br \/>\n&nbsp;<br \/>\nPor favor cont\u00e1ctenos con cualquier pregunta que pueda tener relacionada con nuestras ofertas o nuestros productos. Esperamos escuchar c\u00f3mo podemos marcar la diferencia para usted.<br \/>\n&nbsp;<br \/>\n\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f391-o5\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"391\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/es\/wp-json\/wp\/v2\/posts\/476#wpcf7-f391-o5\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"391\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.5\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f391-o5\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<p><label> <\/label>\n<\/p>\n<h2>Contacto\n<\/h2>\n<p>&nbsp;<br \/>\n<label> Por favor cont\u00e1ctenos con cualquier pregunta que pueda tener relacionada con nuestras ofertas o nuestros productos <\/label>\n<\/p>\n<p><label> Escriba a <a href=\"mailto:info@seasolar.ch\">info@seasolar.ch<\/a> o complete el siguiente formulario y nos pondremos en contacto con usted: <\/label>\n<\/p>\n<p><label> Nombre *<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span><\/label>\n<\/p>\n<p><label> N\u00famero de tel\u00e9fono *<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"tel-826\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-tel\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"tel\" name=\"tel-826\" \/><\/span><\/label>\n<\/p>\n<p><label> Tu correo electr\u00f3nico *<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span><\/label>\n<\/p>\n<p><label> Sujeto *<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-subject\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-subject\" \/><\/span> <\/label>\n<\/p>\n<p><label> Mensaje *<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" name=\"your-message\"><\/textarea><\/span> <\/label>\n<\/p>\n<p><label> * campo requerido <\/label>\n<\/p>\n<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"ENVIAR\" \/>\n<\/p>\n<p><label><\/label>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n<br \/>\n&nbsp;<\/p>\n<!-- sktbuilder starter --><script type=\"text\/javascript\" src=\"https:\/\/seasolar.ch\/wp-content\/plugins\/skt-builder\/sktbuilder\/sktbuilder-frontend-starter.js\"><\/script><script type=\"text\/javascript\" src=\"https:\/\/seasolar.ch\/wp-content\/plugins\/skt-builder\/sktbuilder-wordpress-driver.js\"><\/script><script type=\"text\/javascript\"> var starter = new SktbuilderStarter({\"mode\": \"prod\", \"skip\":[\"jquery\",\"underscore\",\"backbone\"],\"sktbuilderUrl\": \"https:\/\/seasolar.ch\/wp-content\/plugins\/skt-builder\/sktbuilder\/\", \"driver\": new SktbuilderWordpressDriver({\"ajaxUrl\": \"https:\/\/seasolar.ch\/wp-admin\/admin-ajax.php\", \"iframeUrl\": \"https:\/\/seasolar.ch\/es\/offerta-impianto-fotovoltaico-chiavi-in-mano-3kw-basic\/?sktbuilder=true\", \"pageId\": 476,  \"nonce\": \"b7bccc9063\", \"pages\": [], \"page\": \"Offerta Impianto fotovoltaico chiavi in mano 3kW BASIC\" }) });<\/script><!-- end sktbuilder starter -->","protected":false},"excerpt":{"rendered":"<p>Offerta Impianto fotovoltaico \u00abchiavi in mano\u00bb 3 kW BASIC Price on request Seasolar offre la possibilit\u00e0 di scegliere quattro linee di offerta chiavi in mano (BASIC, SMART, PREMIUM, ULTRA) con la garanzia del miglior servizio di installazione eseguito da tecnici specializzati per il massimo dell\u2019efficienza e della sicurezza: tutti gli impianti sono garantiti per 24<br \/><a class=\"moretag\" href=\"https:\/\/seasolar.ch\/es\/offerta-impianto-fotovoltaico-chiavi-in-mano-3kw-basic\/\">+ Read More<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[26,25,112],"tags":[28,29,30,31,32,33,36,37,38,39,40,41,42,43,44,45,46,47,48,49,50,51,53,54,55,56],"class_list":["post-476","post","type-post","status-publish","format-standard","hentry","category-offer-residential-pv-system","category-offers","category-power-3kw","tag-costi-fotovoltaico","tag-costi-impianti-fotovoltaici","tag-costi-pannelli-solari","tag-costo-fotovoltaico","tag-costo-impianto-fotovoltaico","tag-costo-pannelli-solari","tag-offerte-fotovoltaico","tag-offerte-impianti-fotovoltaici","tag-offerte-impianto-fotovoltaico","tag-offerte-pannelli-solari","tag-preventivi-fotovoltaico","tag-preventivi-impianti-fotovoltaici","tag-preventivi-pannelli-solari","tag-preventivo-fotovoltaico","tag-preventivo-impianto-fotovoltaico","tag-preventivo-pannelli-solari","tag-prezzi-fotovoltaico","tag-prezzi-impianti-fotovoltaici","tag-prezzi-pannelli-solari","tag-prezzo-fotovoltaico","tag-prezzo-impianto-fotovoltaico","tag-prezzo-pannelli-solari","tag-vendita-fotovoltaico","tag-vendita-impianti-fotovoltaici","tag-vendita-impianto-fotovoltaico","tag-vendita-pannelli-solari"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Offerta Impianto fotovoltaico chiavi in mano 3kW BASIC - Seasolar Swiss<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/seasolar.ch\/offerta-impianto-fotovoltaico-chiavi-in-mano-3kw-basic\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Offerta Impianto fotovoltaico chiavi in mano 3kW BASIC\" \/>\n<meta property=\"og:description\" content=\"Offerta Impianto fotovoltaico \u00abchiavi in mano\u00bb 3 kW BASIC Price on request Seasolar offre la possibilit\u00e0 di scegliere quattro linee di offerta chiavi in mano (BASIC, SMART, PREMIUM, ULTRA) con la garanzia del miglior servizio di installazione eseguito da tecnici specializzati per il massimo dell\u2019efficienza e della sicurezza: tutti gli impianti sono garantiti per 24+ Read More\" \/>\n<meta property=\"og:url\" content=\"https:\/\/seasolar.ch\/offerta-impianto-fotovoltaico-chiavi-in-mano-3kw-basic\/\" \/>\n<meta property=\"og:site_name\" content=\"Seasolar Swiss\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/seasolargroup\" \/>\n<meta property=\"article:published_time\" content=\"2018-11-06T23:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/seasolar.ch\/wp-content\/uploads\/2025\/09\/PYLON-USB2000BPLUS-2.jpg?fit=670%2C400&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"670\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Seasolar Swiss\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@seasolargroup\" \/>\n<meta name=\"twitter:site\" content=\"@seasolargroup\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Seasolar Swiss\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"18 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/seasolar.ch\\\/offerta-impianto-fotovoltaico-chiavi-in-mano-3kw-basic\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/seasolar.ch\\\/offerta-impianto-fotovoltaico-chiavi-in-mano-3kw-basic\\\/\"},\"author\":{\"name\":\"Seasolar Swiss\",\"@id\":\"https:\\\/\\\/seasolar.ch\\\/#\\\/schema\\\/person\\\/6ff7cd8c09e51bbd963d0fd0a933945d\"},\"headline\":\"Offerta Impianto fotovoltaico chiavi in mano 3kW BASIC\",\"datePublished\":\"2018-11-06T23:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/seasolar.ch\\\/offerta-impianto-fotovoltaico-chiavi-in-mano-3kw-basic\\\/\"},\"wordCount\":3698,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/seasolar.ch\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/seasolar.ch\\\/offerta-impianto-fotovoltaico-chiavi-in-mano-3kw-basic\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/seasolargroup.com\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/AEG_poly_60_cells-207x300.png\",\"keywords\":[\"costi fotovoltaico\",\"costi impianti fotovoltaici\",\"costi pannelli solari\",\"costo fotovoltaico\",\"costo impianto fotovoltaico\",\"costo pannelli solari\",\"offerte fotovoltaico\",\"offerte impianti fotovoltaici\",\"offerte impianto fotovoltaico\",\"offerte pannelli solari\",\"preventivi fotovoltaico\",\"preventivi impianti fotovoltaici\",\"preventivi pannelli solari\",\"preventivo fotovoltaico\",\"preventivo impianto fotovoltaico\",\"preventivo pannelli solari\",\"prezzi fotovoltaico\",\"prezzi impianti fotovoltaici\",\"prezzi pannelli solari\",\"prezzo fotovoltaico\",\"prezzo impianto fotovoltaico\",\"prezzo pannelli solari\",\"vendita fotovoltaico\",\"vendita impianti fotovoltaici\",\"vendita impianto fotovoltaico\",\"vendita pannelli solari\"],\"articleSection\":[\"Oferta sistema fotovoltaico residencial\",\"Ofertas\",\"Power 3kW\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/seasolar.ch\\\/offerta-impianto-fotovoltaico-chiavi-in-mano-3kw-basic\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/seasolar.ch\\\/offerta-impianto-fotovoltaico-chiavi-in-mano-3kw-basic\\\/\",\"url\":\"https:\\\/\\\/seasolar.ch\\\/offerta-impianto-fotovoltaico-chiavi-in-mano-3kw-basic\\\/\",\"name\":\"Offerta Impianto fotovoltaico chiavi in mano 3kW BASIC - Seasolar Swiss\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/seasolar.ch\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/seasolar.ch\\\/offerta-impianto-fotovoltaico-chiavi-in-mano-3kw-basic\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/seasolar.ch\\\/offerta-impianto-fotovoltaico-chiavi-in-mano-3kw-basic\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/seasolargroup.com\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/AEG_poly_60_cells-207x300.png\",\"datePublished\":\"2018-11-06T23:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/seasolar.ch\\\/offerta-impianto-fotovoltaico-chiavi-in-mano-3kw-basic\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/seasolar.ch\\\/offerta-impianto-fotovoltaico-chiavi-in-mano-3kw-basic\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/seasolar.ch\\\/offerta-impianto-fotovoltaico-chiavi-in-mano-3kw-basic\\\/#primaryimage\",\"url\":\"https:\\\/\\\/seasolargroup.com\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/AEG_poly_60_cells-207x300.png\",\"contentUrl\":\"https:\\\/\\\/seasolargroup.com\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/AEG_poly_60_cells-207x300.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/seasolar.ch\\\/offerta-impianto-fotovoltaico-chiavi-in-mano-3kw-basic\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/seasolar.ch\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Offerta Impianto fotovoltaico chiavi in mano 3kW BASIC\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/seasolar.ch\\\/#website\",\"url\":\"https:\\\/\\\/seasolar.ch\\\/\",\"name\":\"Seasolar Swiss\",\"description\":\"Dal 2008 impianti fotovoltaici &quot;chiavi in mano&quot;\",\"publisher\":{\"@id\":\"https:\\\/\\\/seasolar.ch\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/seasolar.ch\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/seasolar.ch\\\/#organization\",\"name\":\"Seasolar Swiss\",\"url\":\"https:\\\/\\\/seasolar.ch\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/seasolar.ch\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/seasolar.ch\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/cropped-seasolar_logo_2024_social.png\",\"contentUrl\":\"https:\\\/\\\/seasolar.ch\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/cropped-seasolar_logo_2024_social.png\",\"width\":512,\"height\":512,\"caption\":\"Seasolar Swiss\"},\"image\":{\"@id\":\"https:\\\/\\\/seasolar.ch\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/seasolargroup\",\"https:\\\/\\\/x.com\\\/seasolargroup\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/seasolar-group-news\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCVrmhrGih_bFnpj0as_vDuQ\",\"https:\\\/\\\/www.instagram.com\\\/fotovoltaico_seasolar\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/seasolar.ch\\\/#\\\/schema\\\/person\\\/6ff7cd8c09e51bbd963d0fd0a933945d\",\"name\":\"Seasolar Swiss\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ea12c6ae3ba2d3c3a39d1e66beb67868a738b85d04b9d89fdd142f88a6dab475?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ea12c6ae3ba2d3c3a39d1e66beb67868a738b85d04b9d89fdd142f88a6dab475?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ea12c6ae3ba2d3c3a39d1e66beb67868a738b85d04b9d89fdd142f88a6dab475?s=96&d=mm&r=g\",\"caption\":\"Seasolar Swiss\"},\"sameAs\":[\"https:\\\/\\\/seasolar.ch\"],\"url\":\"https:\\\/\\\/seasolar.ch\\\/es\\\/author\\\/seasolarswiss\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Offerta Impianto fotovoltaico chiavi in mano 3kW BASIC - Seasolar Swiss","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/seasolar.ch\/offerta-impianto-fotovoltaico-chiavi-in-mano-3kw-basic\/","og_locale":"es_ES","og_type":"article","og_title":"Offerta Impianto fotovoltaico chiavi in mano 3kW BASIC","og_description":"Offerta Impianto fotovoltaico \u00abchiavi in mano\u00bb 3 kW BASIC Price on request Seasolar offre la possibilit\u00e0 di scegliere quattro linee di offerta chiavi in mano (BASIC, SMART, PREMIUM, ULTRA) con la garanzia del miglior servizio di installazione eseguito da tecnici specializzati per il massimo dell\u2019efficienza e della sicurezza: tutti gli impianti sono garantiti per 24+ Read More","og_url":"https:\/\/seasolar.ch\/offerta-impianto-fotovoltaico-chiavi-in-mano-3kw-basic\/","og_site_name":"Seasolar Swiss","article_publisher":"https:\/\/www.facebook.com\/seasolargroup","article_published_time":"2018-11-06T23:00:00+00:00","og_image":[{"width":670,"height":400,"url":"https:\/\/i0.wp.com\/seasolar.ch\/wp-content\/uploads\/2025\/09\/PYLON-USB2000BPLUS-2.jpg?fit=670%2C400&ssl=1","type":"image\/jpeg"}],"author":"Seasolar Swiss","twitter_card":"summary_large_image","twitter_creator":"@seasolargroup","twitter_site":"@seasolargroup","twitter_misc":{"Escrito por":"Seasolar Swiss","Tiempo de lectura":"18 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/seasolar.ch\/offerta-impianto-fotovoltaico-chiavi-in-mano-3kw-basic\/#article","isPartOf":{"@id":"https:\/\/seasolar.ch\/offerta-impianto-fotovoltaico-chiavi-in-mano-3kw-basic\/"},"author":{"name":"Seasolar Swiss","@id":"https:\/\/seasolar.ch\/#\/schema\/person\/6ff7cd8c09e51bbd963d0fd0a933945d"},"headline":"Offerta Impianto fotovoltaico chiavi in mano 3kW BASIC","datePublished":"2018-11-06T23:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/seasolar.ch\/offerta-impianto-fotovoltaico-chiavi-in-mano-3kw-basic\/"},"wordCount":3698,"commentCount":0,"publisher":{"@id":"https:\/\/seasolar.ch\/#organization"},"image":{"@id":"https:\/\/seasolar.ch\/offerta-impianto-fotovoltaico-chiavi-in-mano-3kw-basic\/#primaryimage"},"thumbnailUrl":"https:\/\/seasolargroup.com\/wp-content\/uploads\/2018\/06\/AEG_poly_60_cells-207x300.png","keywords":["costi fotovoltaico","costi impianti fotovoltaici","costi pannelli solari","costo fotovoltaico","costo impianto fotovoltaico","costo pannelli solari","offerte fotovoltaico","offerte impianti fotovoltaici","offerte impianto fotovoltaico","offerte pannelli solari","preventivi fotovoltaico","preventivi impianti fotovoltaici","preventivi pannelli solari","preventivo fotovoltaico","preventivo impianto fotovoltaico","preventivo pannelli solari","prezzi fotovoltaico","prezzi impianti fotovoltaici","prezzi pannelli solari","prezzo fotovoltaico","prezzo impianto fotovoltaico","prezzo pannelli solari","vendita fotovoltaico","vendita impianti fotovoltaici","vendita impianto fotovoltaico","vendita pannelli solari"],"articleSection":["Oferta sistema fotovoltaico residencial","Ofertas","Power 3kW"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/seasolar.ch\/offerta-impianto-fotovoltaico-chiavi-in-mano-3kw-basic\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/seasolar.ch\/offerta-impianto-fotovoltaico-chiavi-in-mano-3kw-basic\/","url":"https:\/\/seasolar.ch\/offerta-impianto-fotovoltaico-chiavi-in-mano-3kw-basic\/","name":"Offerta Impianto fotovoltaico chiavi in mano 3kW BASIC - Seasolar Swiss","isPartOf":{"@id":"https:\/\/seasolar.ch\/#website"},"primaryImageOfPage":{"@id":"https:\/\/seasolar.ch\/offerta-impianto-fotovoltaico-chiavi-in-mano-3kw-basic\/#primaryimage"},"image":{"@id":"https:\/\/seasolar.ch\/offerta-impianto-fotovoltaico-chiavi-in-mano-3kw-basic\/#primaryimage"},"thumbnailUrl":"https:\/\/seasolargroup.com\/wp-content\/uploads\/2018\/06\/AEG_poly_60_cells-207x300.png","datePublished":"2018-11-06T23:00:00+00:00","breadcrumb":{"@id":"https:\/\/seasolar.ch\/offerta-impianto-fotovoltaico-chiavi-in-mano-3kw-basic\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/seasolar.ch\/offerta-impianto-fotovoltaico-chiavi-in-mano-3kw-basic\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/seasolar.ch\/offerta-impianto-fotovoltaico-chiavi-in-mano-3kw-basic\/#primaryimage","url":"https:\/\/seasolargroup.com\/wp-content\/uploads\/2018\/06\/AEG_poly_60_cells-207x300.png","contentUrl":"https:\/\/seasolargroup.com\/wp-content\/uploads\/2018\/06\/AEG_poly_60_cells-207x300.png"},{"@type":"BreadcrumbList","@id":"https:\/\/seasolar.ch\/offerta-impianto-fotovoltaico-chiavi-in-mano-3kw-basic\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/seasolar.ch\/"},{"@type":"ListItem","position":2,"name":"Offerta Impianto fotovoltaico chiavi in mano 3kW BASIC"}]},{"@type":"WebSite","@id":"https:\/\/seasolar.ch\/#website","url":"https:\/\/seasolar.ch\/","name":"Seasolar Swiss","description":"Dal 2008 impianti fotovoltaici &quot;chiavi in mano&quot;","publisher":{"@id":"https:\/\/seasolar.ch\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/seasolar.ch\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/seasolar.ch\/#organization","name":"Seasolar Swiss","url":"https:\/\/seasolar.ch\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/seasolar.ch\/#\/schema\/logo\/image\/","url":"https:\/\/seasolar.ch\/wp-content\/uploads\/2025\/08\/cropped-seasolar_logo_2024_social.png","contentUrl":"https:\/\/seasolar.ch\/wp-content\/uploads\/2025\/08\/cropped-seasolar_logo_2024_social.png","width":512,"height":512,"caption":"Seasolar Swiss"},"image":{"@id":"https:\/\/seasolar.ch\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/seasolargroup","https:\/\/x.com\/seasolargroup","https:\/\/www.linkedin.com\/in\/seasolar-group-news\/","https:\/\/www.youtube.com\/channel\/UCVrmhrGih_bFnpj0as_vDuQ","https:\/\/www.instagram.com\/fotovoltaico_seasolar\/"]},{"@type":"Person","@id":"https:\/\/seasolar.ch\/#\/schema\/person\/6ff7cd8c09e51bbd963d0fd0a933945d","name":"Seasolar Swiss","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/ea12c6ae3ba2d3c3a39d1e66beb67868a738b85d04b9d89fdd142f88a6dab475?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ea12c6ae3ba2d3c3a39d1e66beb67868a738b85d04b9d89fdd142f88a6dab475?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ea12c6ae3ba2d3c3a39d1e66beb67868a738b85d04b9d89fdd142f88a6dab475?s=96&d=mm&r=g","caption":"Seasolar Swiss"},"sameAs":["https:\/\/seasolar.ch"],"url":"https:\/\/seasolar.ch\/es\/author\/seasolarswiss\/"}]}},"jetpack_featured_media_url":"","jetpack_likes_enabled":true,"jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/seasolar.ch\/es\/wp-json\/wp\/v2\/posts\/476","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/seasolar.ch\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/seasolar.ch\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/seasolar.ch\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/seasolar.ch\/es\/wp-json\/wp\/v2\/comments?post=476"}],"version-history":[{"count":0,"href":"https:\/\/seasolar.ch\/es\/wp-json\/wp\/v2\/posts\/476\/revisions"}],"wp:attachment":[{"href":"https:\/\/seasolar.ch\/es\/wp-json\/wp\/v2\/media?parent=476"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/seasolar.ch\/es\/wp-json\/wp\/v2\/categories?post=476"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/seasolar.ch\/es\/wp-json\/wp\/v2\/tags?post=476"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}